{"id":367794,"date":"2026-06-29T07:30:01","date_gmt":"2026-06-29T07:30:01","guid":{"rendered":""},"modified":"2026-06-29T13:46:45","modified_gmt":"2026-06-29T13:46:45","slug":"legal-notice","status":"publish","type":"page","link":"https:\/\/v2charge.com\/be-fr\/legal-notice\/","title":{"rendered":"Avertissement l\u00e9gal et politique de confidentialit\u00e9"},"content":{"rendered":"<p><strong>Politique de confidentialit\u00e9, Utilisation des cookies et plus d&rsquo;informations<\/strong><\/p>\n<p>Politique de Confidentialit\u00e9 de V2Charge (V2C). Ce site web est la propri\u00e9t\u00e9 de NEGOCIOS INTELIGENTES 7EXPERIENCE S.L. (ci-apr\u00e8s \u201cV2C\u201d), dont le si\u00e8ge est situ\u00e9 Avenida Cam\u00ed Nou 268 Xirivella (Valence), immatricul\u00e9e sous le CIF N\u00ba B98496706.<br \/>\nConform\u00e9ment \u00e0 la Loi 15\/99 du 13 d\u00e9cembre sur la protection des donn\u00e9es, nous vous informons que toutes vos donn\u00e9es font partie d&rsquo;un fichier appartenant \u00e0 NEGOCIOS INTELIGENTES 7 EXPERIENCE S.L. dans le but de r\u00e9pondre \u00e0 toute question que vous pourriez avoir, de g\u00e9rer la relation commerciale et de vous envoyer des nouvelles concernant les produits et services de la Soci\u00e9t\u00e9 par tout moyen, y compris \u00e9lectronique.<\/p>\n<p>Nous ne stockons pas de donn\u00e9es de carte de cr\u00e9dit ni ne partageons les donn\u00e9es personnelles des utilisateurs avec des tiers. Nous ne vendons, louons ou c\u00e9dons des donn\u00e9es personnelles pouvant vous identifier, ni ne le ferons \u00e0 l&rsquo;avenir, \u00e0 des tiers sans votre consentement. Cependant, dans certains cas, nous pouvons utiliser des fournisseurs, des partenaires ou des agences pour traiter vos informations personnelles en notre nom, toujours en suivant nos instructions et en exigeant le respect des normes de s\u00e9curit\u00e9 les plus strictes.<\/p>\n<p>Si \u00e0 l&rsquo;avenir nous lan\u00e7ons de nouvelles activit\u00e9s d\u00e9pendant de notre soci\u00e9t\u00e9 (NEGOCIOS INTELIGENTES 7EXPERIENCE S.L.) ou d&rsquo;autres soci\u00e9t\u00e9s qui lui sont associ\u00e9es et qui sont li\u00e9es aux produits et services fournis par V2C, nous utiliserons vos donn\u00e9es personnelles pour vous informer de leur lancement et pour faciliter leur utilisation ou leur souscription. Dans ce cas, nous vous en informerons \u00e0 l&rsquo;avance afin que vous puissiez, le cas \u00e9ch\u00e9ant, annuler vos donn\u00e9es dans ces services.<\/p>\n<p>Lorsque vous vous inscrivez ou nous contactez via notre site web, nous recueillons deux types d&rsquo;informations : 1) Informations personnelles telles que votre nom, adresse, num\u00e9ro de t\u00e9l\u00e9phone et adresse e-mail que vous nous fournissez volontairement. 2) L&rsquo;adresse IP de votre ordinateur et les informations anonymes collect\u00e9es par les cookies lorsque vous naviguez sur notre site web pour nous aider \u00e0 comprendre comment am\u00e9liorer notre site et nos services. Si vous souhaitez en savoir plus sur la fa\u00e7on dont nous utilisons nos cookies, veuillez visiter le site web \/es\/Legal\/Cookies\u00a0\u00bb.<\/p>\n<p><strong>Vos droits<\/strong><\/p>\n<p>La r\u00e9glementation sur la protection des donn\u00e9es exige, entre autres, que vos donn\u00e9es personnelles soient trait\u00e9es de mani\u00e8re loyale, appropri\u00e9e, exacte et de fa\u00e7on non excessive. Les donn\u00e9es personnelles doivent \u00eatre tenues \u00e0 jour et conserv\u00e9es pendant une p\u00e9riode qui ne d\u00e9passe pas ce qui est n\u00e9cessaire. De plus, elles doivent \u00eatre conserv\u00e9es de mani\u00e8re s\u00e9curis\u00e9e pour \u00e9viter tout acc\u00e8s non autoris\u00e9 par d&rsquo;autres personnes et vous avez le droit de savoir quelles informations nous avons sur vous et de corriger les donn\u00e9es incorrectes. \u00c0 tout moment, vous pouvez exercer vos droits d&rsquo;acc\u00e8s, de rectification, d&rsquo;opposition ou d&rsquo;annulation en envoyant votre demande \u00e0 info@v2charge.com ou par courrier postal \u00e0 NEGOCIOS INTELIGENTES 7EXPERIENCE S.L., Avenida Cam\u00ed Nou 268 Xirivella 46950, en joignant une copie de votre Document National d&rsquo;Identit\u00e9 (DNI) ou un document \u00e9quivalent.\u00a0\u00bb<\/p>\n<p><strong>Cookies<\/strong><\/p>\n<p>Nous utilisons parfois une fonctionnalit\u00e9 de votre navigateur Internet appel\u00e9e \u201ccookie\u201d sur le site web de V2C. Un \u201ccookie\u201d est un tr\u00e8s petit fichier texte que votre navigateur place sur le disque dur de votre ordinateur, ce qui nous permet de tirer le meilleur parti de votre visite sur notre site web et d&rsquo;am\u00e9liorer l&rsquo;exp\u00e9rience utilisateur. Un \u201ccookie\u201d peut \u00eatre consid\u00e9r\u00e9 comme une carte d&rsquo;identit\u00e9 qui informe un site web lorsque vous \u00eates revenu.<\/p>\n<p>V2C traite toutes les informations avec le plus grand soin et s\u00e9curit\u00e9. En aucun cas nous ne stockons ou ne traitons vos donn\u00e9es bancaires ou de carte de cr\u00e9dit, mais ces informations seront directement g\u00e9r\u00e9es par nos fournisseurs de moyens de paiement, qui respectent toutes les exigences de s\u00e9curit\u00e9 et l\u00e9gales les plus strictes. Veuillez noter que nous ne vous contacterons que pour vous demander confirmation des d\u00e9tails de votre compte lorsque votre carte sera refus\u00e9e au moment du paiement. Lorsque nous vous contacterons, nous ne vous demanderons jamais votre mot de passe ni votre code PIN de carte. Nous vous conseillons de ne jamais entrer votre num\u00e9ro de compte ou votre mot de passe dans un e-mail ou apr\u00e8s avoir cliqu\u00e9 sur un lien provenant d&rsquo;un e-mail.<\/p>\n<p><strong>Modification de la politique de confidentialit\u00e9<\/strong><\/p>\n<p>La mise \u00e0 jour et la modification de cette politique de confidentialit\u00e9 seront r\u00e9gies par les r\u00e8gles pr\u00e9vues dans les conditions d&rsquo;utilisation pour la mise \u00e0 jour et la modification de celles-ci.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Politique de confidentialit\u00e9, Utilisation des cookies et plus d&rsquo;informations Politique de Confidentialit\u00e9 de V2Charge (V2C). Ce site web est la propri\u00e9t\u00e9 de NEGOCIOS INTELIGENTES 7EXPERIENCE S.L. (ci-apr\u00e8s \u201cV2C\u201d), dont le si\u00e8ge est situ\u00e9 Avenida Cam\u00ed Nou 268 Xirivella (Valence), immatricul\u00e9e sous le CIF N\u00ba B98496706. Conform\u00e9ment \u00e0 la Loi 15\/99 du 13 d\u00e9cembre sur la &#8230; <a title=\"Avertissement l\u00e9gal et politique de confidentialit\u00e9\" class=\"read-more\" href=\"https:\/\/v2charge.com\/be-fr\/legal-notice\/\" aria-label=\"Read more about Avertissement l\u00e9gal et politique de confidentialit\u00e9\">Lire la suite<\/a><\/p>\n","protected":false},"author":1,"featured_media":170354,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_eb_attr":"","content-type":"","_uag_custom_page_level_css":"","footnotes":""},"class_list":["post-367794","page","type-page","status-publish","has-post-thumbnail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avertissement l\u00e9gal et politique de confidentialit\u00e9 - V2C Points de Recharge<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avertissement l\u00e9gal et politique de confidentialit\u00e9 - V2C Points de Recharge\" \/>\n<meta property=\"og:description\" content=\"Politique de confidentialit\u00e9, Utilisation des cookies et plus d&rsquo;informations Politique de Confidentialit\u00e9 de V2Charge (V2C). Ce site web est la propri\u00e9t\u00e9 de NEGOCIOS INTELIGENTES 7EXPERIENCE S.L. (ci-apr\u00e8s \u201cV2C\u201d), dont le si\u00e8ge est situ\u00e9 Avenida Cam\u00ed Nou 268 Xirivella (Valence), immatricul\u00e9e sous le CIF N\u00ba B98496706. Conform\u00e9ment \u00e0 la Loi 15\/99 du 13 d\u00e9cembre sur la ... Lire la suite\" \/>\n<meta property=\"og:url\" content=\"https:\/\/v2charge.com\/be-fr\/legal-notice\/\" \/>\n<meta property=\"og:site_name\" content=\"V2C\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/V2C.Charge\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-29T13:46:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/v2charge.com\/wp-content\/uploads\/2024\/07\/v2c-electric-chargers.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@V2C_Charge\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/v2charge.com\\\/be-fr\\\/legal-notice\\\/\",\"url\":\"https:\\\/\\\/v2charge.com\\\/be-fr\\\/legal-notice\\\/\",\"name\":\"Avertissement l\u00e9gal et politique de confidentialit\u00e9 - V2C Points de Recharge\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/v2charge.com\\\/be-fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/v2charge.com\\\/be-fr\\\/legal-notice\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/v2charge.com\\\/be-fr\\\/legal-notice\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/v2charge.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/v2c-electric-chargers.jpg\",\"datePublished\":\"2026-06-29T07:30:01+00:00\",\"dateModified\":\"2026-06-29T13:46:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/v2charge.com\\\/be-fr\\\/legal-notice\\\/#breadcrumb\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/v2charge.com\\\/be-fr\\\/legal-notice\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/v2charge.com\\\/be-fr\\\/legal-notice\\\/#primaryimage\",\"url\":\"https:\\\/\\\/v2charge.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/v2c-electric-chargers.jpg\",\"contentUrl\":\"https:\\\/\\\/v2charge.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/v2c-electric-chargers.jpg\",\"width\":1200,\"height\":675,\"caption\":\"V2C Electric Chargers\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/v2charge.com\\\/be-fr\\\/legal-notice\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"V2C\",\"item\":\"https:\\\/\\\/v2charge.com\\\/be-fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avertissement l\u00e9gal et politique de confidentialit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/v2charge.com\\\/be-fr\\\/#website\",\"url\":\"https:\\\/\\\/v2charge.com\\\/be-fr\\\/\",\"name\":\"V2C\",\"description\":\"#CargandoElMa\u00f1ana\",\"publisher\":{\"@id\":\"https:\\\/\\\/v2charge.com\\\/be-fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/v2charge.com\\\/be-fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/v2charge.com\\\/be-fr\\\/#organization\",\"name\":\"V2C\",\"url\":\"https:\\\/\\\/v2charge.com\\\/be-fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/v2charge.com\\\/be-fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/v2charge.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-v2c-charge-logo-menu.png\",\"contentUrl\":\"https:\\\/\\\/v2charge.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-v2c-charge-logo-menu.png\",\"width\":984,\"height\":431,\"caption\":\"V2C\"},\"image\":{\"@id\":\"https:\\\/\\\/v2charge.com\\\/be-fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/V2C.Charge\",\"https:\\\/\\\/x.com\\\/V2C_Charge\",\"https:\\\/\\\/www.instagram.com\\\/v2c.charge\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@V2C\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/v2c-chargers\\\/\"],\"contactPoint\":[{\"@type\":\"ContactPoint\",\"contactType\":\"customer support\",\"telephone\":\"+34960654554\",\"email\":\"info@v2charge.com\",\"availableLanguage\":[\"Spanish\",\"English\",\"Portuguese\",\"French\"]},{\"@type\":\"ContactPoint\",\"contactType\":\"sales\",\"telephone\":\"+34960654554\",\"email\":\"info@v2charge.com\",\"availableLanguage\":[\"Spanish\",\"English\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avertissement l\u00e9gal et politique de confidentialit\u00e9 - V2C Points de Recharge","robots":{"index":"noindex","follow":"follow"},"og_locale":"fr_FR","og_type":"article","og_title":"Avertissement l\u00e9gal et politique de confidentialit\u00e9 - V2C Points de Recharge","og_description":"Politique de confidentialit\u00e9, Utilisation des cookies et plus d&rsquo;informations Politique de Confidentialit\u00e9 de V2Charge (V2C). Ce site web est la propri\u00e9t\u00e9 de NEGOCIOS INTELIGENTES 7EXPERIENCE S.L. (ci-apr\u00e8s \u201cV2C\u201d), dont le si\u00e8ge est situ\u00e9 Avenida Cam\u00ed Nou 268 Xirivella (Valence), immatricul\u00e9e sous le CIF N\u00ba B98496706. Conform\u00e9ment \u00e0 la Loi 15\/99 du 13 d\u00e9cembre sur la ... Lire la suite","og_url":"https:\/\/v2charge.com\/be-fr\/legal-notice\/","og_site_name":"V2C","article_publisher":"https:\/\/www.facebook.com\/V2C.Charge","article_modified_time":"2026-06-29T13:46:45+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/v2charge.com\/wp-content\/uploads\/2024\/07\/v2c-electric-chargers.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@V2C_Charge","twitter_misc":{"Dur\u00e9e de lecture est.":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/v2charge.com\/be-fr\/legal-notice\/","url":"https:\/\/v2charge.com\/be-fr\/legal-notice\/","name":"Avertissement l\u00e9gal et politique de confidentialit\u00e9 - V2C Points de Recharge","isPartOf":{"@id":"https:\/\/v2charge.com\/be-fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/v2charge.com\/be-fr\/legal-notice\/#primaryimage"},"image":{"@id":"https:\/\/v2charge.com\/be-fr\/legal-notice\/#primaryimage"},"thumbnailUrl":"https:\/\/v2charge.com\/wp-content\/uploads\/2024\/07\/v2c-electric-chargers.jpg","datePublished":"2026-06-29T07:30:01+00:00","dateModified":"2026-06-29T13:46:45+00:00","breadcrumb":{"@id":"https:\/\/v2charge.com\/be-fr\/legal-notice\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/v2charge.com\/be-fr\/legal-notice\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/v2charge.com\/be-fr\/legal-notice\/#primaryimage","url":"https:\/\/v2charge.com\/wp-content\/uploads\/2024\/07\/v2c-electric-chargers.jpg","contentUrl":"https:\/\/v2charge.com\/wp-content\/uploads\/2024\/07\/v2c-electric-chargers.jpg","width":1200,"height":675,"caption":"V2C Electric Chargers"},{"@type":"BreadcrumbList","@id":"https:\/\/v2charge.com\/be-fr\/legal-notice\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"V2C","item":"https:\/\/v2charge.com\/be-fr\/"},{"@type":"ListItem","position":2,"name":"Avertissement l\u00e9gal et politique de confidentialit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/v2charge.com\/be-fr\/#website","url":"https:\/\/v2charge.com\/be-fr\/","name":"V2C","description":"#CargandoElMa\u00f1ana","publisher":{"@id":"https:\/\/v2charge.com\/be-fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/v2charge.com\/be-fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"},{"@type":"Organization","@id":"https:\/\/v2charge.com\/be-fr\/#organization","name":"V2C","url":"https:\/\/v2charge.com\/be-fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/v2charge.com\/be-fr\/#\/schema\/logo\/image\/","url":"https:\/\/v2charge.com\/wp-content\/uploads\/2024\/11\/cropped-v2c-charge-logo-menu.png","contentUrl":"https:\/\/v2charge.com\/wp-content\/uploads\/2024\/11\/cropped-v2c-charge-logo-menu.png","width":984,"height":431,"caption":"V2C"},"image":{"@id":"https:\/\/v2charge.com\/be-fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/V2C.Charge","https:\/\/x.com\/V2C_Charge","https:\/\/www.instagram.com\/v2c.charge\/","https:\/\/www.youtube.com\/@V2C","https:\/\/www.linkedin.com\/company\/v2c-chargers\/"],"contactPoint":[{"@type":"ContactPoint","contactType":"customer support","telephone":"+34960654554","email":"info@v2charge.com","availableLanguage":["Spanish","English","Portuguese","French"]},{"@type":"ContactPoint","contactType":"sales","telephone":"+34960654554","email":"info@v2charge.com","availableLanguage":["Spanish","English"]}]}]}},"uagb_featured_image_src":{"full":["https:\/\/v2charge.com\/wp-content\/uploads\/2024\/07\/v2c-electric-chargers.jpg",1200,675,false],"thumbnail":["https:\/\/v2charge.com\/wp-content\/uploads\/2024\/07\/v2c-electric-chargers-150x150.jpg",150,150,true],"medium":["https:\/\/v2charge.com\/wp-content\/uploads\/2024\/07\/v2c-electric-chargers-300x169.jpg",300,169,true],"medium_large":["https:\/\/v2charge.com\/wp-content\/uploads\/2024\/07\/v2c-electric-chargers-768x432.jpg",768,432,true],"large":["https:\/\/v2charge.com\/wp-content\/uploads\/2024\/07\/v2c-electric-chargers-1024x576.jpg",1024,576,true],"gs-tiny":["https:\/\/v2charge.com\/wp-content\/uploads\/2024\/07\/v2c-electric-chargers.jpg",50,28,false],"xl":["https:\/\/v2charge.com\/wp-content\/uploads\/2024\/07\/v2c-electric-chargers.jpg",1200,675,false],"xxl":["https:\/\/v2charge.com\/wp-content\/uploads\/2024\/07\/v2c-electric-chargers.jpg",1200,675,false],"xxxl":["https:\/\/v2charge.com\/wp-content\/uploads\/2024\/07\/v2c-electric-chargers.jpg",1200,675,false],"xxxxl":["https:\/\/v2charge.com\/wp-content\/uploads\/2024\/07\/v2c-electric-chargers.jpg",1200,675,false],"xxxxxl":["https:\/\/v2charge.com\/wp-content\/uploads\/2024\/07\/v2c-electric-chargers.jpg",1200,675,false],"1536x1536":["https:\/\/v2charge.com\/wp-content\/uploads\/2024\/07\/v2c-electric-chargers.jpg",1200,675,false],"2048x2048":["https:\/\/v2charge.com\/wp-content\/uploads\/2024\/07\/v2c-electric-chargers.jpg",1200,675,false]},"uagb_author_info":{"display_name":"V2C","author_link":"https:\/\/v2charge.com\/be-fr\/author\/root_k4eu7ki8\/"},"uagb_comment_info":0,"uagb_excerpt":"Politique de confidentialit\u00e9, Utilisation des cookies et plus d&rsquo;informations Politique de Confidentialit\u00e9 de V2Charge (V2C). Ce site web est la propri\u00e9t\u00e9 de NEGOCIOS INTELIGENTES 7EXPERIENCE S.L. (ci-apr\u00e8s \u201cV2C\u201d), dont le si\u00e8ge est situ\u00e9 Avenida Cam\u00ed Nou 268 Xirivella (Valence), immatricul\u00e9e sous le CIF N\u00ba B98496706. Conform\u00e9ment \u00e0 la Loi 15\/99 du 13 d\u00e9cembre sur la&hellip;","_links":{"self":[{"href":"https:\/\/v2charge.com\/be-fr\/wp-json\/wp\/v2\/pages\/367794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/v2charge.com\/be-fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/v2charge.com\/be-fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/v2charge.com\/be-fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/v2charge.com\/be-fr\/wp-json\/wp\/v2\/comments?post=367794"}],"version-history":[{"count":0,"href":"https:\/\/v2charge.com\/be-fr\/wp-json\/wp\/v2\/pages\/367794\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/v2charge.com\/be-fr\/wp-json\/wp\/v2\/media\/170354"}],"wp:attachment":[{"href":"https:\/\/v2charge.com\/be-fr\/wp-json\/wp\/v2\/media?parent=367794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}