{"id":365612,"date":"2026-06-25T12:40:06","date_gmt":"2026-06-25T10:40:06","guid":{"rendered":""},"modified":"2026-06-25T16:04:29","modified_gmt":"2026-06-25T14:04:29","slug":"v2c-presenta-trydan-bidirezionale-a-power2drive-2026-v2l-modalita-isola-v2g-e-v2h","status":"publish","type":"post","link":"https:\/\/v2charge.com\/it\/v2c-presenta-trydan-bidirezionale-a-power2drive-2026-v2l-modalita-isola-v2g-e-v2h\/","title":{"rendered":"V2C presenta Trydan bidirezionale a Power2Drive 2026: V2L Island Mode, V2G e V2H"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Oggi, da Power2Drive 2026 a Monaco, presentiamo il lancio pi\u00f9 importante della storia di V2C. <strong>Trydan fa il salto verso la bidirezionalit\u00e0.<\/strong> Il tuo veicolo elettrico non consuma pi\u00f9 solo energia \u2014 pu\u00f2 anche restituirla alla tua casa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Abbiamo trascorso mesi a preparare questo momento. Settimane a svelare novit\u00e0 nel nostro cammino verso Power2Drive. E oggi, finalmente, possiamo raccontare tutto su <a href=\"https:\/\/v2charge.com\/it\/trydan-bidireccional\/\" type=\"link\" id=\"https:\/\/v2charge.com\/es\/trydan-bidireccional\/\">Trydan bidirezionale<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sotto il claim <strong>&#8220;L&#8217;energia non va pi\u00f9 in una sola direzione&#8221;<\/strong>, presentiamo ufficialmente <strong>Trydan V2L Modalit\u00e0 isola<\/strong>, la prima soluzione bidirezionale di Trydan disponibile, e annunciamo <strong>Trydan V2G e V2H<\/strong>, che arriveranno nel Q1 2027.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Scopri di pi\u00f9 su Trydan V2L Island Mode<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Cos&#8217;\u00e8<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Trydan V2L Modalit\u00e0 isola ti consente di alimentare tutta la tua abitazione con l&#8217;energia immagazzinata nella batteria del tuo veicolo elettrico.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Perch\u00e9 si chiama &#8220;Island Mode&#8221;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La casa viene isolata dalla rete elettrica durante il processo.<\/strong> Questa disconnessione \u00e8 obbligatoria per motivi di sicurezza. Trydan invia l&#8217;ordine di disconnessione a un <em>Smart switch<\/em> installato nel quadro generale, e tutto avviene in modo automatico, senza intervento manuale.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"523\" src=\"https:\/\/v2charge.com\/wp-content\/uploads\/2026\/06\/bidirectional-charge-trydan-v2c-ev-charger-1024x523.jpg\" alt=\"\" class=\"wp-image-364440\" srcset=\"https:\/\/v2charge.com\/wp-content\/uploads\/2026\/06\/bidirectional-charge-trydan-v2c-ev-charger-1024x523.jpg 1024w, https:\/\/v2charge.com\/wp-content\/uploads\/2026\/06\/bidirectional-charge-trydan-v2c-ev-charger-300x153.jpg 300w, https:\/\/v2charge.com\/wp-content\/uploads\/2026\/06\/bidirectional-charge-trydan-v2c-ev-charger-768x392.jpg 768w, https:\/\/v2charge.com\/wp-content\/uploads\/2026\/06\/bidirectional-charge-trydan-v2c-ev-charger-50x26.jpg 50w, https:\/\/v2charge.com\/wp-content\/uploads\/2026\/06\/bidirectional-charge-trydan-v2c-ev-charger-1600x818.jpg 1600w, https:\/\/v2charge.com\/wp-content\/uploads\/2026\/06\/bidirectional-charge-trydan-v2c-ev-charger-1536x785.jpg 1536w, https:\/\/v2charge.com\/wp-content\/uploads\/2026\/06\/bidirectional-charge-trydan-v2c-ev-charger.jpg 1900w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Come funziona passo dopo passo<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>1. Attivi la modalit\u00e0 dall&#8217;app gratuita V2C Cloud<\/strong>. Selezioni il tuo veicolo e attivi la V2L Island Mode.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2. Disconnessione automatica dalla rete<\/strong>. Trydan invia l&#8217;ordine alla protezione elettrica del tuo quadro generale. L&#8217;abitazione viene isolata dalla rete in modo sicuro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3. La tua auto alimenta la tua casa<\/strong>. L&#8217;energia della batteria del tuo veicolo scorre attraverso Trydan verso l&#8217;intero impianto della tua abitazione. Luce, riscaldamento, elettrodomestici essenziali \u2014 tutto funziona con l&#8217;energia della tua auto.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Per quali situazioni \u00e8 utile<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">In caso di <strong>interruzioni di fornitura<\/strong> o <strong>situazioni di emergenza<\/strong>, la modalit\u00e0 isola consente di utilizzare l&#8217;energia immagazzinata nel veicolo elettrico per alimentare dispositivi e impianti essenziali. Grazie a questa funzione, la tua auto diventa una fonte di energia indipendente, fornendo elettricit\u00e0 anche quando la rete elettrica non \u00e8 disponibile.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Considerazioni importanti<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Trydan V2L Island Mode \u00e8 progettato per abitazioni unifamiliari.<\/strong> La soluzione richiede che il caricatore e l&#8217;installazione domestica condividano un unico quadro elettrico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante Island Mode, l&#8217;abitazione \u00e8 disconnessa dalla rete, quindi non \u00e8 possibile consumare energia dalla rete e dal veicolo contemporaneamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inoltre, l&#8217;uso di questa nuova funzionalit\u00e0 <strong>richiede che il veicolo elettrico sia compatibile con la tecnologia V2L<\/strong>. Se hai dubbi sulla compatibilit\u00e0 del tuo modello, ti consigliamo di contattarci prima dell&#8217;installazione.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"528\" src=\"https:\/\/v2charge.com\/wp-content\/uploads\/2026\/06\/v2l-island-mode-explatanation-bidirectional-charger-v2c-trydan-1024x528.jpg\" alt=\"\" class=\"wp-image-364778\" srcset=\"https:\/\/v2charge.com\/wp-content\/uploads\/2026\/06\/v2l-island-mode-explatanation-bidirectional-charger-v2c-trydan-1024x528.jpg 1024w, https:\/\/v2charge.com\/wp-content\/uploads\/2026\/06\/v2l-island-mode-explatanation-bidirectional-charger-v2c-trydan-300x155.jpg 300w, https:\/\/v2charge.com\/wp-content\/uploads\/2026\/06\/v2l-island-mode-explatanation-bidirectional-charger-v2c-trydan-768x396.jpg 768w, https:\/\/v2charge.com\/wp-content\/uploads\/2026\/06\/v2l-island-mode-explatanation-bidirectional-charger-v2c-trydan-50x26.jpg 50w, https:\/\/v2charge.com\/wp-content\/uploads\/2026\/06\/v2l-island-mode-explatanation-bidirectional-charger-v2c-trydan-1600x824.jpg 1600w, https:\/\/v2charge.com\/wp-content\/uploads\/2026\/06\/v2l-island-mode-explatanation-bidirectional-charger-v2c-trydan-1536x791.jpg 1536w, https:\/\/v2charge.com\/wp-content\/uploads\/2026\/06\/v2l-island-mode-explatanation-bidirectional-charger-v2c-trydan.jpg 1900w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Trydan V2G e V2H \u2014 disponibile nel Q1 2027<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Trydan V2G e V2H \u00e8 l&#8217;evoluzione naturale di V2L Island Mode e della completa bidirezionalit\u00e0 che sta per arrivare.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">V2G \u2014 Veicolo alla Rete<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Con V2G, l&#8217;energia immagazzinata nella batteria del tuo veicolo viene iniettata direttamente nella rete elettrica. <strong>Carica di notte con tariffa bassa o con surplus solare, e vendi quell&#8217;energia alla rete quando il prezzo dell&#8217;elettricit\u00e0 aumenta.<\/strong> La tua auto genera valore economico anche quando \u00e8 parcheggiata.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">V2H \u2014 Veicolo a Casa<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Con V2H, <strong>l&#8217;energia del veicolo alimenta la casa<\/strong> in modo bidirezionale completo, senza la necessit\u00e0 di disconnettersi dalla rete. <strong>Il sistema gestisce automaticamente quando utilizzare l&#8217;energia dell&#8217;auto e quando attingere dalla rete<\/strong>, ottimizzando il consumo e riducendo la bolletta senza che tu debba fare nulla.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Perch\u00e9 arriva nel 2027 e non prima?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">V2G e V2H richiedono due condizioni che sono ancora in fase di maturazione nel settore:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Veicoli compatibili<\/strong> \u2014 \u00e8 necessario che i veicoli supportino il protocollo di comunicazione bidirezionale ISO 15118-20. Ci sono sempre pi\u00f9 modelli che lo incorporano, ma l&#8217;adozione di massa \u00e8 ancora in fase di sviluppo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Normativa regolatoria<\/strong> \u2014 ogni paese dell&#8217;UE sta adattando il proprio quadro normativo per consentire l&#8217;immissione di energia dai veicoli nella rete. Questo processo sta avanzando e si prevede che sar\u00e0 sufficientemente sviluppato a partire dal primo trimestre del 2027.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La modalit\u00e0 V2L isola \u00e8 la nostra risposta a quell&#8217;attesa \u2014 una soluzione che gi\u00e0 oggi offre reale indipendenza energetica all&#8217;utente domestico.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">L&#8217;ecosistema software, incluso di serie<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Tutta la gestione bidirezionale \u00e8 controllata dall&#8217;app gratuita <strong>V2C Cloud<\/strong>, inclusa senza costi aggiuntivi con ogni caricatore Trydan. Attivazione della V2L Island Mode, controllo dell&#8217;energia, monitoraggio in tempo reale e avvisi \u2014 tutto dal cellulare.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In V2C crediamo in un&#8217;energia pi\u00f9 intelligente, efficiente e connessa. <strong>La bidirezionalit\u00e0 \u00e8 un passo avanti<\/strong> verso un ecosistema in cui il veicolo elettrico non solo si ricarica, ma protegge e supporta anche la tua casa quando ne hai pi\u00f9 bisogno. Una tecnologia pensata per offrire tranquillit\u00e0, autonomia e controllo energetico in qualsiasi situazione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oggi, da Power2Drive 2026 a Monaco, presentiamo il lancio pi\u00f9 importante della storia di V2C. Trydan fa il salto verso la bidirezionalit\u00e0. Il tuo veicolo elettrico non consuma pi\u00f9 solo energia \u2014 pu\u00f2 anche restituirla alla tua casa. Abbiamo trascorso mesi a preparare questo momento. Settimane a svelare novit\u00e0 nel nostro cammino verso Power2Drive. E &#8230; <a title=\"V2C presenta Trydan bidirezionale a Power2Drive 2026: V2L Island Mode, V2G e V2H\" class=\"read-more\" href=\"https:\/\/v2charge.com\/it\/v2c-presenta-trydan-bidirezionale-a-power2drive-2026-v2l-modalita-isola-v2g-e-v2h\/\" aria-label=\"Per saperne di pi\u00f9 su V2C presenta Trydan bidirezionale a Power2Drive 2026: V2L Island Mode, V2G e V2H\">Leggi tutto<\/a><\/p>\n","protected":false},"author":400,"featured_media":365553,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","content-type":"","_uag_custom_page_level_css":"","footnotes":""},"categories":[4],"tags":[],"class_list":["post-365612","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-e-mobility"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>V2C presenta Trydan Bidirezionale: V2L e V2G\/V2H<\/title>\n<meta name=\"description\" content=\"V2C presenta ufficialmente la versione di Trydan Bidirezionale: V2L Island Mode, V2G e V2H | Scopri Trydan Bidirezionale\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/v2charge.com\/it\/v2c-presenta-trydan-bidirezionale-a-power2drive-2026-v2l-modalita-isola-v2g-e-v2h\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"V2C presenta Trydan Bidirezionale: V2L e V2G\/V2H\" \/>\n<meta property=\"og:description\" content=\"V2C presenta ufficialmente la versione di Trydan Bidirezionale: V2L Island Mode, V2G e V2H | Scopri Trydan Bidirezionale\" \/>\n<meta property=\"og:url\" content=\"https:\/\/v2charge.com\/it\/v2c-presenta-trydan-bidirezionale-a-power2drive-2026-v2l-modalita-isola-v2g-e-v2h\/\" \/>\n<meta property=\"og:site_name\" content=\"V2C\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/V2C.Charge\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-25T10:40:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-25T14:04:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/v2charge.com\/wp-content\/uploads\/2026\/06\/lars-hoffmann-todoselectricos-v2c-power2drive-trydan-bidirectional-global-lunch.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1632\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"V2C\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@V2C_Charge\" \/>\n<meta name=\"twitter:site\" content=\"@V2C_Charge\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"V2C\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/v2charge.com\\\/it\\\/v2c-presenta-trydan-bidirezionale-a-power2drive-2026-v2l-modalita-isola-v2g-e-v2h\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/v2charge.com\\\/it\\\/v2c-presenta-trydan-bidirezionale-a-power2drive-2026-v2l-modalita-isola-v2g-e-v2h\\\/\"},\"author\":{\"name\":\"V2C\",\"@id\":\"https:\\\/\\\/v2charge.com\\\/it\\\/#\\\/schema\\\/person\\\/47b01868f6351f17635b441e66044aaa\"},\"headline\":\"V2C presenta Trydan bidirezionale a Power2Drive 2026: V2L Island Mode, V2G e V2H\",\"datePublished\":\"2026-06-25T10:40:06+00:00\",\"dateModified\":\"2026-06-25T14:04:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/v2charge.com\\\/it\\\/v2c-presenta-trydan-bidirezionale-a-power2drive-2026-v2l-modalita-isola-v2g-e-v2h\\\/\"},\"wordCount\":768,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/v2charge.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/v2charge.com\\\/it\\\/v2c-presenta-trydan-bidirezionale-a-power2drive-2026-v2l-modalita-isola-v2g-e-v2h\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/v2charge.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/lars-hoffmann-todoselectricos-v2c-power2drive-trydan-bidirectional-global-lunch.jpg\",\"articleSection\":[\"e-Mobility\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/v2charge.com\\\/it\\\/v2c-presenta-trydan-bidirezionale-a-power2drive-2026-v2l-modalita-isola-v2g-e-v2h\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/v2charge.com\\\/it\\\/v2c-presenta-trydan-bidirezionale-a-power2drive-2026-v2l-modalita-isola-v2g-e-v2h\\\/\",\"url\":\"https:\\\/\\\/v2charge.com\\\/it\\\/v2c-presenta-trydan-bidirezionale-a-power2drive-2026-v2l-modalita-isola-v2g-e-v2h\\\/\",\"name\":\"V2C presenta Trydan Bidirezionale: V2L e V2G\\\/V2H\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/v2charge.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/v2charge.com\\\/it\\\/v2c-presenta-trydan-bidirezionale-a-power2drive-2026-v2l-modalita-isola-v2g-e-v2h\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/v2charge.com\\\/it\\\/v2c-presenta-trydan-bidirezionale-a-power2drive-2026-v2l-modalita-isola-v2g-e-v2h\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/v2charge.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/lars-hoffmann-todoselectricos-v2c-power2drive-trydan-bidirectional-global-lunch.jpg\",\"datePublished\":\"2026-06-25T10:40:06+00:00\",\"dateModified\":\"2026-06-25T14:04:29+00:00\",\"description\":\"V2C presenta ufficialmente la versione di Trydan Bidirezionale: V2L Island Mode, V2G e V2H | Scopri Trydan Bidirezionale\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/v2charge.com\\\/it\\\/v2c-presenta-trydan-bidirezionale-a-power2drive-2026-v2l-modalita-isola-v2g-e-v2h\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/v2charge.com\\\/it\\\/v2c-presenta-trydan-bidirezionale-a-power2drive-2026-v2l-modalita-isola-v2g-e-v2h\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/v2charge.com\\\/it\\\/v2c-presenta-trydan-bidirezionale-a-power2drive-2026-v2l-modalita-isola-v2g-e-v2h\\\/#primaryimage\",\"url\":\"https:\\\/\\\/v2charge.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/lars-hoffmann-todoselectricos-v2c-power2drive-trydan-bidirectional-global-lunch.jpg\",\"contentUrl\":\"https:\\\/\\\/v2charge.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/lars-hoffmann-todoselectricos-v2c-power2drive-trydan-bidirectional-global-lunch.jpg\",\"width\":1632,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/v2charge.com\\\/it\\\/v2c-presenta-trydan-bidirezionale-a-power2drive-2026-v2l-modalita-isola-v2g-e-v2h\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"V2C\",\"item\":\"https:\\\/\\\/v2charge.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Notizie V2C\",\"item\":\"https:\\\/\\\/v2charge.com\\\/it\\\/notizie-v2c\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"V2C presenta Trydan bidirezionale a Power2Drive 2026: V2L Island Mode, V2G e V2H\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/v2charge.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/v2charge.com\\\/it\\\/\",\"name\":\"V2C\",\"description\":\"#CargandoElMa\u00f1ana\",\"publisher\":{\"@id\":\"https:\\\/\\\/v2charge.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/v2charge.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/v2charge.com\\\/it\\\/#organization\",\"name\":\"V2C\",\"url\":\"https:\\\/\\\/v2charge.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/v2charge.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/v2charge.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-v2c-charge-logo-menu.png\",\"contentUrl\":\"https:\\\/\\\/v2charge.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-v2c-charge-logo-menu.png\",\"width\":984,\"height\":431,\"caption\":\"V2C\"},\"image\":{\"@id\":\"https:\\\/\\\/v2charge.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/V2C.Charge\",\"https:\\\/\\\/x.com\\\/V2C_Charge\",\"https:\\\/\\\/www.instagram.com\\\/v2c.charge\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@V2C\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/v2c-chargers\\\/\"],\"contactPoint\":[{\"@type\":\"ContactPoint\",\"contactType\":\"customer support\",\"telephone\":\"+34960654554\",\"email\":\"info@v2charge.com\",\"availableLanguage\":[\"Spanish\",\"English\",\"Portuguese\",\"French\"]},{\"@type\":\"ContactPoint\",\"contactType\":\"sales\",\"telephone\":\"+34960654554\",\"email\":\"info@v2charge.com\",\"availableLanguage\":[\"Spanish\",\"English\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/v2charge.com\\\/it\\\/#\\\/schema\\\/person\\\/47b01868f6351f17635b441e66044aaa\",\"name\":\"V2C\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a91128c4c0d2f4d63bd586301fdec6cc9aa49c885839b25d1c62700f529f267c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a91128c4c0d2f4d63bd586301fdec6cc9aa49c885839b25d1c62700f529f267c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a91128c4c0d2f4d63bd586301fdec6cc9aa49c885839b25d1c62700f529f267c?s=96&d=mm&r=g\",\"caption\":\"V2C\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"V2C presenta Trydan Bidirezionale: V2L e V2G\/V2H","description":"V2C presenta ufficialmente la versione di Trydan Bidirezionale: V2L Island Mode, V2G e V2H | Scopri Trydan Bidirezionale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/v2charge.com\/it\/v2c-presenta-trydan-bidirezionale-a-power2drive-2026-v2l-modalita-isola-v2g-e-v2h\/","og_locale":"it_IT","og_type":"article","og_title":"V2C presenta Trydan Bidirezionale: V2L e V2G\/V2H","og_description":"V2C presenta ufficialmente la versione di Trydan Bidirezionale: V2L Island Mode, V2G e V2H | Scopri Trydan Bidirezionale","og_url":"https:\/\/v2charge.com\/it\/v2c-presenta-trydan-bidirezionale-a-power2drive-2026-v2l-modalita-isola-v2g-e-v2h\/","og_site_name":"V2C","article_publisher":"https:\/\/www.facebook.com\/V2C.Charge","article_published_time":"2026-06-25T10:40:06+00:00","article_modified_time":"2026-06-25T14:04:29+00:00","og_image":[{"width":1632,"height":1024,"url":"https:\/\/v2charge.com\/wp-content\/uploads\/2026\/06\/lars-hoffmann-todoselectricos-v2c-power2drive-trydan-bidirectional-global-lunch.jpg","type":"image\/jpeg"}],"author":"V2C","twitter_card":"summary_large_image","twitter_creator":"@V2C_Charge","twitter_site":"@V2C_Charge","twitter_misc":{"Scritto da":"V2C","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/v2charge.com\/it\/v2c-presenta-trydan-bidirezionale-a-power2drive-2026-v2l-modalita-isola-v2g-e-v2h\/#article","isPartOf":{"@id":"https:\/\/v2charge.com\/it\/v2c-presenta-trydan-bidirezionale-a-power2drive-2026-v2l-modalita-isola-v2g-e-v2h\/"},"author":{"name":"V2C","@id":"https:\/\/v2charge.com\/it\/#\/schema\/person\/47b01868f6351f17635b441e66044aaa"},"headline":"V2C presenta Trydan bidirezionale a Power2Drive 2026: V2L Island Mode, V2G e V2H","datePublished":"2026-06-25T10:40:06+00:00","dateModified":"2026-06-25T14:04:29+00:00","mainEntityOfPage":{"@id":"https:\/\/v2charge.com\/it\/v2c-presenta-trydan-bidirezionale-a-power2drive-2026-v2l-modalita-isola-v2g-e-v2h\/"},"wordCount":768,"commentCount":0,"publisher":{"@id":"https:\/\/v2charge.com\/it\/#organization"},"image":{"@id":"https:\/\/v2charge.com\/it\/v2c-presenta-trydan-bidirezionale-a-power2drive-2026-v2l-modalita-isola-v2g-e-v2h\/#primaryimage"},"thumbnailUrl":"https:\/\/v2charge.com\/wp-content\/uploads\/2026\/06\/lars-hoffmann-todoselectricos-v2c-power2drive-trydan-bidirectional-global-lunch.jpg","articleSection":["e-Mobility"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/v2charge.com\/it\/v2c-presenta-trydan-bidirezionale-a-power2drive-2026-v2l-modalita-isola-v2g-e-v2h\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/v2charge.com\/it\/v2c-presenta-trydan-bidirezionale-a-power2drive-2026-v2l-modalita-isola-v2g-e-v2h\/","url":"https:\/\/v2charge.com\/it\/v2c-presenta-trydan-bidirezionale-a-power2drive-2026-v2l-modalita-isola-v2g-e-v2h\/","name":"V2C presenta Trydan Bidirezionale: V2L e V2G\/V2H","isPartOf":{"@id":"https:\/\/v2charge.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/v2charge.com\/it\/v2c-presenta-trydan-bidirezionale-a-power2drive-2026-v2l-modalita-isola-v2g-e-v2h\/#primaryimage"},"image":{"@id":"https:\/\/v2charge.com\/it\/v2c-presenta-trydan-bidirezionale-a-power2drive-2026-v2l-modalita-isola-v2g-e-v2h\/#primaryimage"},"thumbnailUrl":"https:\/\/v2charge.com\/wp-content\/uploads\/2026\/06\/lars-hoffmann-todoselectricos-v2c-power2drive-trydan-bidirectional-global-lunch.jpg","datePublished":"2026-06-25T10:40:06+00:00","dateModified":"2026-06-25T14:04:29+00:00","description":"V2C presenta ufficialmente la versione di Trydan Bidirezionale: V2L Island Mode, V2G e V2H | Scopri Trydan Bidirezionale","breadcrumb":{"@id":"https:\/\/v2charge.com\/it\/v2c-presenta-trydan-bidirezionale-a-power2drive-2026-v2l-modalita-isola-v2g-e-v2h\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/v2charge.com\/it\/v2c-presenta-trydan-bidirezionale-a-power2drive-2026-v2l-modalita-isola-v2g-e-v2h\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/v2charge.com\/it\/v2c-presenta-trydan-bidirezionale-a-power2drive-2026-v2l-modalita-isola-v2g-e-v2h\/#primaryimage","url":"https:\/\/v2charge.com\/wp-content\/uploads\/2026\/06\/lars-hoffmann-todoselectricos-v2c-power2drive-trydan-bidirectional-global-lunch.jpg","contentUrl":"https:\/\/v2charge.com\/wp-content\/uploads\/2026\/06\/lars-hoffmann-todoselectricos-v2c-power2drive-trydan-bidirectional-global-lunch.jpg","width":1632,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/v2charge.com\/it\/v2c-presenta-trydan-bidirezionale-a-power2drive-2026-v2l-modalita-isola-v2g-e-v2h\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"V2C","item":"https:\/\/v2charge.com\/it\/"},{"@type":"ListItem","position":2,"name":"Notizie V2C","item":"https:\/\/v2charge.com\/it\/notizie-v2c\/"},{"@type":"ListItem","position":3,"name":"V2C presenta Trydan bidirezionale a Power2Drive 2026: V2L Island Mode, V2G e V2H"}]},{"@type":"WebSite","@id":"https:\/\/v2charge.com\/it\/#website","url":"https:\/\/v2charge.com\/it\/","name":"V2C","description":"#CargandoElMa\u00f1ana","publisher":{"@id":"https:\/\/v2charge.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/v2charge.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/v2charge.com\/it\/#organization","name":"V2C","url":"https:\/\/v2charge.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/v2charge.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/v2charge.com\/wp-content\/uploads\/2024\/11\/cropped-v2c-charge-logo-menu.png","contentUrl":"https:\/\/v2charge.com\/wp-content\/uploads\/2024\/11\/cropped-v2c-charge-logo-menu.png","width":984,"height":431,"caption":"V2C"},"image":{"@id":"https:\/\/v2charge.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/V2C.Charge","https:\/\/x.com\/V2C_Charge","https:\/\/www.instagram.com\/v2c.charge\/","https:\/\/www.youtube.com\/@V2C","https:\/\/www.linkedin.com\/company\/v2c-chargers\/"],"contactPoint":[{"@type":"ContactPoint","contactType":"customer support","telephone":"+34960654554","email":"info@v2charge.com","availableLanguage":["Spanish","English","Portuguese","French"]},{"@type":"ContactPoint","contactType":"sales","telephone":"+34960654554","email":"info@v2charge.com","availableLanguage":["Spanish","English"]}]},{"@type":"Person","@id":"https:\/\/v2charge.com\/it\/#\/schema\/person\/47b01868f6351f17635b441e66044aaa","name":"V2C","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a91128c4c0d2f4d63bd586301fdec6cc9aa49c885839b25d1c62700f529f267c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a91128c4c0d2f4d63bd586301fdec6cc9aa49c885839b25d1c62700f529f267c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a91128c4c0d2f4d63bd586301fdec6cc9aa49c885839b25d1c62700f529f267c?s=96&d=mm&r=g","caption":"V2C"}}]}},"uagb_featured_image_src":{"full":["https:\/\/v2charge.com\/wp-content\/uploads\/2026\/06\/lars-hoffmann-todoselectricos-v2c-power2drive-trydan-bidirectional-global-lunch.jpg",1632,1024,false],"thumbnail":["https:\/\/v2charge.com\/wp-content\/uploads\/2026\/06\/lars-hoffmann-todoselectricos-v2c-power2drive-trydan-bidirectional-global-lunch-150x150.jpg",150,150,true],"medium":["https:\/\/v2charge.com\/wp-content\/uploads\/2026\/06\/lars-hoffmann-todoselectricos-v2c-power2drive-trydan-bidirectional-global-lunch-300x188.jpg",300,188,true],"medium_large":["https:\/\/v2charge.com\/wp-content\/uploads\/2026\/06\/lars-hoffmann-todoselectricos-v2c-power2drive-trydan-bidirectional-global-lunch-768x482.jpg",768,482,true],"large":["https:\/\/v2charge.com\/wp-content\/uploads\/2026\/06\/lars-hoffmann-todoselectricos-v2c-power2drive-trydan-bidirectional-global-lunch-1024x643.jpg",1024,643,true],"gs-tiny":["https:\/\/v2charge.com\/wp-content\/uploads\/2026\/06\/lars-hoffmann-todoselectricos-v2c-power2drive-trydan-bidirectional-global-lunch-50x31.jpg",50,31,true],"xl":["https:\/\/v2charge.com\/wp-content\/uploads\/2026\/06\/lars-hoffmann-todoselectricos-v2c-power2drive-trydan-bidirectional-global-lunch-1600x1004.jpg",1600,1004,true],"xxl":["https:\/\/v2charge.com\/wp-content\/uploads\/2026\/06\/lars-hoffmann-todoselectricos-v2c-power2drive-trydan-bidirectional-global-lunch.jpg",1632,1024,false],"xxxl":["https:\/\/v2charge.com\/wp-content\/uploads\/2026\/06\/lars-hoffmann-todoselectricos-v2c-power2drive-trydan-bidirectional-global-lunch.jpg",1632,1024,false],"xxxxl":["https:\/\/v2charge.com\/wp-content\/uploads\/2026\/06\/lars-hoffmann-todoselectricos-v2c-power2drive-trydan-bidirectional-global-lunch.jpg",1632,1024,false],"xxxxxl":["https:\/\/v2charge.com\/wp-content\/uploads\/2026\/06\/lars-hoffmann-todoselectricos-v2c-power2drive-trydan-bidirectional-global-lunch.jpg",1632,1024,false],"1536x1536":["https:\/\/v2charge.com\/wp-content\/uploads\/2026\/06\/lars-hoffmann-todoselectricos-v2c-power2drive-trydan-bidirectional-global-lunch-1536x964.jpg",1536,964,true],"2048x2048":["https:\/\/v2charge.com\/wp-content\/uploads\/2026\/06\/lars-hoffmann-todoselectricos-v2c-power2drive-trydan-bidirectional-global-lunch.jpg",1632,1024,false]},"uagb_author_info":{"display_name":"V2C","author_link":"https:\/\/v2charge.com\/it\/author\/marketing\/"},"uagb_comment_info":0,"uagb_excerpt":"Oggi, da Power2Drive 2026 a Monaco, presentiamo il lancio pi\u00f9 importante della storia di V2C. Trydan fa il salto verso la bidirezionalit\u00e0. Il tuo veicolo elettrico non consuma pi\u00f9 solo energia \u2014 pu\u00f2 anche restituirla alla tua casa. Abbiamo trascorso mesi a preparare questo momento. Settimane a svelare novit\u00e0 nel nostro cammino verso Power2Drive. E&hellip;","_links":{"self":[{"href":"https:\/\/v2charge.com\/it\/wp-json\/wp\/v2\/posts\/365612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/v2charge.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/v2charge.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/v2charge.com\/it\/wp-json\/wp\/v2\/users\/400"}],"replies":[{"embeddable":true,"href":"https:\/\/v2charge.com\/it\/wp-json\/wp\/v2\/comments?post=365612"}],"version-history":[{"count":1,"href":"https:\/\/v2charge.com\/it\/wp-json\/wp\/v2\/posts\/365612\/revisions"}],"predecessor-version":[{"id":365973,"href":"https:\/\/v2charge.com\/it\/wp-json\/wp\/v2\/posts\/365612\/revisions\/365973"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/v2charge.com\/it\/wp-json\/wp\/v2\/media\/365553"}],"wp:attachment":[{"href":"https:\/\/v2charge.com\/it\/wp-json\/wp\/v2\/media?parent=365612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/v2charge.com\/it\/wp-json\/wp\/v2\/categories?post=365612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/v2charge.com\/it\/wp-json\/wp\/v2\/tags?post=365612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}